{"id":10469,"date":"2025-11-11T03:04:57","date_gmt":"2025-11-11T03:04:57","guid":{"rendered":"https:\/\/www.hangzhiprecision.com\/?p=10469"},"modified":"2025-11-11T03:05:02","modified_gmt":"2025-11-11T03:05:02","slug":"portable-programmable-dc-voltage-source","status":"publish","type":"post","link":"https:\/\/www.hangzhiprecision.com\/de_at\/pnews\/portable-programmable-dc-voltage-source\/","title":{"rendered":"Neu | Tragbare programmierbare Gleichspannungsquelle, 0-10KV, 0,01% Genauigkeit"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"10469\" class=\"elementor elementor-10469\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-11edce2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"11edce2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f77beb8\" data-id=\"f77beb8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f978a6b elementor-widget elementor-widget-image\" data-id=\"f978a6b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1000\" height=\"686\" src=\"https:\/\/www.hangzhiprecision.com\/wp-content\/uploads\/2025\/11\/hz6061y.jpg\" class=\"attachment-full size-full wp-image-10480\" alt=\"Tragbare programmierbare Gleichspannungsquelle HZ6061Y\" srcset=\"https:\/\/www.hangzhiprecision.com\/wp-content\/uploads\/2025\/11\/hz6061y.jpg 1000w, https:\/\/www.hangzhiprecision.com\/wp-content\/uploads\/2025\/11\/hz6061y-300x206.jpg 300w, https:\/\/www.hangzhiprecision.com\/wp-content\/uploads\/2025\/11\/hz6061y-768x527.jpg 768w, https:\/\/www.hangzhiprecision.com\/wp-content\/uploads\/2025\/11\/hz6061y-18x12.jpg 18w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-347914d elementor-widget elementor-widget-text-editor\" data-id=\"347914d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Pr\u00e4zise Gleichspannung, Hocheffiziente Kalibrierung, Jederzeit und \u00dcberall.<\/p>\n<p>Die tragbare programmierbare Gleichspannungsquelle HZ6061Y wurde speziell f\u00fcr die Kalibrierung von Gleichspannungsmessger\u00e4ten entwickelt und bietet Pr\u00e4zision, Portabilit\u00e4t und Zuverl\u00e4ssigkeit.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ed7e62d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ed7e62d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b4c2647\" data-id=\"b4c2647\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7e165a4 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"7e165a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Wichtige Technische Parameter<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e0c6605\" data-id=\"e0c6605\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-a04a868 elementor-widget elementor-widget-heading\" data-id=\"a04a868\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">High-Performance DC Output:<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b19215d elementor-widget elementor-widget-text-editor\" data-id=\"b19215d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Hohe Genauigkeit: 0,01 %<br \/>Hohe Stabilit\u00e4t: 0,005 %\/min<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e09d249 elementor-widget elementor-widget-heading\" data-id=\"e09d249\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Multi-Bereich-Kompatibilit\u00e4t<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0dea8f4 elementor-widget elementor-widget-text-editor\" data-id=\"0dea8f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Unterst\u00fctzt einen weiten Bereich der DC-Ausgangsspannung von 0 bis 2000 V und deckt sechs Bereiche ab: 6 V, 20 V, 60 V, 200 V, 1000 V und 2000 V. Der Einstellbereich betr\u00e4gt 0 bis 110 % RG und erf\u00fcllt die Kalibrieranforderungen verschiedener DC-Spannungsmessger\u00e4te.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2d5e644 elementor-widget elementor-widget-heading\" data-id=\"2d5e644\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Leicht und Tragbar &amp; Langlebiges Design:<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b28d61 elementor-widget elementor-widget-text-editor\" data-id=\"3b28d61\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Kompakte Struktur (456\u00d7372\u00d7185 mm)<br \/>Leichter K\u00f6rper von ungef\u00e4hr 10 kg<br \/>Tragbare Industriekonstruktion, druck- und sto\u00dffest. F\u00fchren Sie DC-Kalibrierungsaufgaben jederzeit und \u00fcberall durch.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-960ccc0 elementor-widget elementor-widget-heading\" data-id=\"960ccc0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Einfache und intuitive Touch-Bedienung<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cd69a73 elementor-widget elementor-widget-text-editor\" data-id=\"cd69a73\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Einfache und benutzerfreundliche Oberfl\u00e4che<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b9ed094 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b9ed094\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-175e51d\" data-id=\"175e51d\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-279a0d1 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"279a0d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Anwendungen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-36cb1a0\" data-id=\"36cb1a0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f9b255 elementor-widget elementor-widget-text-editor\" data-id=\"5f9b255\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Industrielle Produktionslinien: Wird als Gleichspannungsreferenzquelle zur raschen Kalibrierung von Voltmeter und Sensoren verwendet.<\/p><p>Laborpr\u00fcfung: Wird als Standardquelle f\u00fcr die messtechnische Verifizierung verwendet.<\/p><p>Vor Ort: Schnelle Spannungskalibrierung zur Beseitigung von Anomalien.<\/p><p>Multifunktional: Abdeckung von industriellen Produktionslinien, Vor-Ort-Tests, Messzentren und Forschungslaboren, um eine effiziente Gleichspannungskalibrierung zu erreichen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2a6946b elementor-widget elementor-widget-video\" data-id=\"2a6946b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtube.com\\\/shorts\\\/7JEY6rikcYs&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5fc20b8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5fc20b8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f5c183f\" data-id=\"f5c183f\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-44e213d elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"44e213d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Tragbare programmierbare Gleichspannungsquelle HZ6061Y<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-4e9125f\" data-id=\"4e9125f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-1cf17d2 elementor-widget elementor-widget-text-editor\" data-id=\"1cf17d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Hohe Leistung \u00d7 Hohe Effizienz \u00d7 Hohe Zuverl\u00e4ssigkeit<br \/>Erleben Sie jetzt die neue Wahl f\u00fcr tragbare Hochpr\u00e4zisions-DC-Spannungskalibrierung!<\/p><p>Neue Produkteinf\u00fchrung \u2022 Willkommen zur Anfrage!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-fb9c274 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fb9c274\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ed9ee5a\" data-id=\"ed9ee5a\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9204650 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"9204650\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00dcber Hangzhi<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f9b4b70\" data-id=\"f9b4b70\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-9ec6bd4 elementor-widget elementor-widget-text-editor\" data-id=\"9ec6bd4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/www.hangzhiprecision.com\/de_at\/\"><strong>Shenzhen Hangzhi Pr\u00e4zisionselektronik Co., Ltd.<\/strong><\/a> ist ein technologisch f\u00fchrendes Unternehmen, das sich der Forschung und Entwicklung, der Produktion, dem Vertrieb und der Anpassung von L\u00f6sungen f\u00fcr hochpr\u00e4zise Stromsensoren, Spannungssensoren und hochpr\u00e4zise elektrische Messger\u00e4te widmet. Wir streben danach, eine bekannte Marke von <a href=\"https:\/\/ieeexplore.ieee.org\/document\/8601521\">fluxgate<\/a> Pr\u00e4zisionsstromsensoren und elektrische Pr\u00e4zisionsmessger\u00e4te im Gleichstrombereich und streben die Entwicklung zu einem international f\u00fchrenden Unternehmen der Pr\u00e4zisionselektronik im Bereich der Gleichstromsysteme an.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Precision DC Voltage, High-Efficiency Calibration, Anytime, Anywhere. The HZ6061Y Portable Programmable DC Voltage Source is designed specifically for calibrating DC voltage measurement equipment, offering precision, portability, and reliability. Key Technical Parameters of the Product High-Performance DC Output: High Accuracy: 0.01%High Stability: 0.005%\/min Multi-Range Compatibility: Supports a wide range of DC voltage output from 0 to [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":10480,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[43],"tags":[],"class_list":["post-10469","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pnews"],"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.2 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>New | Portable Programmable DC Voltage Source, 0-10KV, 0.01% Accuracy<\/title>\n<meta name=\"description\" content=\"Hangzhi&#039;s high-precision ppm-level current sensor has high reliability, making high-precision current measurement no longer a problem.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hangzhiprecision.com\/de_at\/pnews\/portable-programmable-dc-voltage-source\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"New | Portable Programmable DC Voltage Source, 0-10KV, 0.01% Accuracy\" \/>\n<meta property=\"og:description\" content=\"Hangzhi&#039;s high-precision ppm-level current sensor has high reliability, making high-precision current measurement no longer a problem.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hangzhiprecision.com\/de_at\/pnews\/portable-programmable-dc-voltage-source\/\" \/>\n<meta property=\"og:site_name\" content=\"Hangzhi Precision\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ShenzhenHangzhi\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-11T03:04:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-11T03:05:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.hangzhiprecision.com\/wp-content\/uploads\/2025\/11\/hz6061y.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"686\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Hangzhi_News\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Hangzhi_News\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.hangzhiprecision.com\\\/pnews\\\/portable-programmable-dc-voltage-source\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hangzhiprecision.com\\\/pnews\\\/portable-programmable-dc-voltage-source\\\/\"},\"author\":{\"name\":\"Hangzhi_News\",\"@id\":\"https:\\\/\\\/www.hangzhiprecision.com\\\/en\\\/#\\\/schema\\\/person\\\/e65df2a2a90a05e3c739bd38da3c3446\"},\"headline\":\"New | Portable Programmable DC Voltage Source, 0-10KV, 0.01% Accuracy\",\"datePublished\":\"2025-11-11T03:04:57+00:00\",\"dateModified\":\"2025-11-11T03:05:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.hangzhiprecision.com\\\/pnews\\\/portable-programmable-dc-voltage-source\\\/\"},\"wordCount\":285,\"publisher\":{\"@id\":\"https:\\\/\\\/www.hangzhiprecision.com\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hangzhiprecision.com\\\/pnews\\\/portable-programmable-dc-voltage-source\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hangzhiprecision.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/hz6061y.jpg\",\"articleSection\":[\"Hangzhi Product New Releases\"],\"inLanguage\":\"de-AT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hangzhiprecision.com\\\/pnews\\\/portable-programmable-dc-voltage-source\\\/\",\"url\":\"https:\\\/\\\/www.hangzhiprecision.com\\\/pnews\\\/portable-programmable-dc-voltage-source\\\/\",\"name\":\"New | Portable Programmable DC Voltage Source, 0-10KV, 0.01% Accuracy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hangzhiprecision.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.hangzhiprecision.com\\\/pnews\\\/portable-programmable-dc-voltage-source\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hangzhiprecision.com\\\/pnews\\\/portable-programmable-dc-voltage-source\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hangzhiprecision.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/hz6061y.jpg\",\"datePublished\":\"2025-11-11T03:04:57+00:00\",\"dateModified\":\"2025-11-11T03:05:02+00:00\",\"description\":\"Hangzhi's high-precision ppm-level current sensor has high reliability, making high-precision current measurement no longer a problem.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.hangzhiprecision.com\\\/pnews\\\/portable-programmable-dc-voltage-source\\\/#breadcrumb\"},\"inLanguage\":\"de-AT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hangzhiprecision.com\\\/pnews\\\/portable-programmable-dc-voltage-source\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-AT\",\"@id\":\"https:\\\/\\\/www.hangzhiprecision.com\\\/pnews\\\/portable-programmable-dc-voltage-source\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.hangzhiprecision.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/hz6061y.jpg\",\"contentUrl\":\"https:\\\/\\\/www.hangzhiprecision.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/hz6061y.jpg\",\"width\":1000,\"height\":686,\"caption\":\"HZ6061Y Portable Programmable DC Voltage Source\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.hangzhiprecision.com\\\/pnews\\\/portable-programmable-dc-voltage-source\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.hangzhiprecision.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"New | Portable Programmable DC Voltage Source, 0-10KV, 0.01% Accuracy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hangzhiprecision.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.hangzhiprecision.com\\\/en\\\/\",\"name\":\"Hangzhi Precision\",\"description\":\"Hangzhi Precision\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.hangzhiprecision.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hangzhiprecision.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-AT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.hangzhiprecision.com\\\/en\\\/#organization\",\"name\":\"Shenzhen Hangzhi Precision Electronics Co., Ltd.\",\"alternateName\":\"Hangzhi Precision\",\"url\":\"https:\\\/\\\/www.hangzhiprecision.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-AT\",\"@id\":\"https:\\\/\\\/www.hangzhiprecision.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.hangzhiprecision.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/logo-en-400x400-1.png\",\"contentUrl\":\"https:\\\/\\\/www.hangzhiprecision.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/logo-en-400x400-1.png\",\"width\":400,\"height\":400,\"caption\":\"Shenzhen Hangzhi Precision Electronics Co., Ltd.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hangzhiprecision.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ShenzhenHangzhi\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.hangzhiprecision.com\\\/en\\\/#\\\/schema\\\/person\\\/e65df2a2a90a05e3c739bd38da3c3446\",\"name\":\"Hangzhi_News\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-AT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/aed6969cd5e350cb9fac46f1f970d78ef8f32b124ab724ee53e19d2b78acdccf?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/aed6969cd5e350cb9fac46f1f970d78ef8f32b124ab724ee53e19d2b78acdccf?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/aed6969cd5e350cb9fac46f1f970d78ef8f32b124ab724ee53e19d2b78acdccf?s=96&d=mm&r=g\",\"caption\":\"Hangzhi_News\"},\"url\":\"https:\\\/\\\/www.hangzhiprecision.com\\\/de_at\\\/author\\\/hangzhi_news\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Neu | Tragbare programmierbare Gleichspannungsquelle, 0-10KV, 0,01% Genauigkeit","description":"Hangzhi's high-precision ppm-level current sensor has high reliability, making high-precision current measurement no longer a problem.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hangzhiprecision.com\/de_at\/pnews\/portable-programmable-dc-voltage-source\/","og_locale":"de_DE","og_type":"article","og_title":"New | Portable Programmable DC Voltage Source, 0-10KV, 0.01% Accuracy","og_description":"Hangzhi's high-precision ppm-level current sensor has high reliability, making high-precision current measurement no longer a problem.","og_url":"https:\/\/www.hangzhiprecision.com\/de_at\/pnews\/portable-programmable-dc-voltage-source\/","og_site_name":"Hangzhi Precision","article_publisher":"https:\/\/www.facebook.com\/ShenzhenHangzhi\/","article_published_time":"2025-11-11T03:04:57+00:00","article_modified_time":"2025-11-11T03:05:02+00:00","og_image":[{"width":1000,"height":686,"url":"https:\/\/www.hangzhiprecision.com\/wp-content\/uploads\/2025\/11\/hz6061y.jpg","type":"image\/jpeg"}],"author":"Hangzhi_News","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Hangzhi_News","Gesch\u00e4tzte Lesezeit":"2 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.hangzhiprecision.com\/pnews\/portable-programmable-dc-voltage-source\/#article","isPartOf":{"@id":"https:\/\/www.hangzhiprecision.com\/pnews\/portable-programmable-dc-voltage-source\/"},"author":{"name":"Hangzhi_News","@id":"https:\/\/www.hangzhiprecision.com\/en\/#\/schema\/person\/e65df2a2a90a05e3c739bd38da3c3446"},"headline":"New | Portable Programmable DC Voltage Source, 0-10KV, 0.01% Accuracy","datePublished":"2025-11-11T03:04:57+00:00","dateModified":"2025-11-11T03:05:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.hangzhiprecision.com\/pnews\/portable-programmable-dc-voltage-source\/"},"wordCount":285,"publisher":{"@id":"https:\/\/www.hangzhiprecision.com\/en\/#organization"},"image":{"@id":"https:\/\/www.hangzhiprecision.com\/pnews\/portable-programmable-dc-voltage-source\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hangzhiprecision.com\/wp-content\/uploads\/2025\/11\/hz6061y.jpg","articleSection":["Hangzhi Product New Releases"],"inLanguage":"de-AT"},{"@type":"WebPage","@id":"https:\/\/www.hangzhiprecision.com\/pnews\/portable-programmable-dc-voltage-source\/","url":"https:\/\/www.hangzhiprecision.com\/pnews\/portable-programmable-dc-voltage-source\/","name":"Neu | Tragbare programmierbare Gleichspannungsquelle, 0-10KV, 0,01% Genauigkeit","isPartOf":{"@id":"https:\/\/www.hangzhiprecision.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hangzhiprecision.com\/pnews\/portable-programmable-dc-voltage-source\/#primaryimage"},"image":{"@id":"https:\/\/www.hangzhiprecision.com\/pnews\/portable-programmable-dc-voltage-source\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hangzhiprecision.com\/wp-content\/uploads\/2025\/11\/hz6061y.jpg","datePublished":"2025-11-11T03:04:57+00:00","dateModified":"2025-11-11T03:05:02+00:00","description":"Hangzhi's high-precision ppm-level current sensor has high reliability, making high-precision current measurement no longer a problem.","breadcrumb":{"@id":"https:\/\/www.hangzhiprecision.com\/pnews\/portable-programmable-dc-voltage-source\/#breadcrumb"},"inLanguage":"de-AT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hangzhiprecision.com\/pnews\/portable-programmable-dc-voltage-source\/"]}]},{"@type":"ImageObject","inLanguage":"de-AT","@id":"https:\/\/www.hangzhiprecision.com\/pnews\/portable-programmable-dc-voltage-source\/#primaryimage","url":"https:\/\/www.hangzhiprecision.com\/wp-content\/uploads\/2025\/11\/hz6061y.jpg","contentUrl":"https:\/\/www.hangzhiprecision.com\/wp-content\/uploads\/2025\/11\/hz6061y.jpg","width":1000,"height":686,"caption":"HZ6061Y Portable Programmable DC Voltage Source"},{"@type":"BreadcrumbList","@id":"https:\/\/www.hangzhiprecision.com\/pnews\/portable-programmable-dc-voltage-source\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.hangzhiprecision.com\/"},{"@type":"ListItem","position":2,"name":"New | Portable Programmable DC Voltage Source, 0-10KV, 0.01% Accuracy"}]},{"@type":"WebSite","@id":"https:\/\/www.hangzhiprecision.com\/en\/#website","url":"https:\/\/www.hangzhiprecision.com\/en\/","name":"Hangzhi Precision","description":"Hangzhi Precision","publisher":{"@id":"https:\/\/www.hangzhiprecision.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hangzhiprecision.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-AT"},{"@type":"Organization","@id":"https:\/\/www.hangzhiprecision.com\/en\/#organization","name":"Shenzhen Hangzhi Pr\u00e4zisionselektronik Co., Ltd.","alternateName":"Hangzhi Precision","url":"https:\/\/www.hangzhiprecision.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"de-AT","@id":"https:\/\/www.hangzhiprecision.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.hangzhiprecision.com\/wp-content\/uploads\/2023\/08\/logo-en-400x400-1.png","contentUrl":"https:\/\/www.hangzhiprecision.com\/wp-content\/uploads\/2023\/08\/logo-en-400x400-1.png","width":400,"height":400,"caption":"Shenzhen Hangzhi Precision Electronics Co., Ltd."},"image":{"@id":"https:\/\/www.hangzhiprecision.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ShenzhenHangzhi\/"]},{"@type":"Person","@id":"https:\/\/www.hangzhiprecision.com\/en\/#\/schema\/person\/e65df2a2a90a05e3c739bd38da3c3446","name":"Hangzhi_News","image":{"@type":"ImageObject","inLanguage":"de-AT","@id":"https:\/\/secure.gravatar.com\/avatar\/aed6969cd5e350cb9fac46f1f970d78ef8f32b124ab724ee53e19d2b78acdccf?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/aed6969cd5e350cb9fac46f1f970d78ef8f32b124ab724ee53e19d2b78acdccf?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/aed6969cd5e350cb9fac46f1f970d78ef8f32b124ab724ee53e19d2b78acdccf?s=96&d=mm&r=g","caption":"Hangzhi_News"},"url":"https:\/\/www.hangzhiprecision.com\/de_at\/author\/hangzhi_news\/"}]}},"_links":{"self":[{"href":"https:\/\/www.hangzhiprecision.com\/de_at\/wp-json\/wp\/v2\/posts\/10469","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hangzhiprecision.com\/de_at\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hangzhiprecision.com\/de_at\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hangzhiprecision.com\/de_at\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hangzhiprecision.com\/de_at\/wp-json\/wp\/v2\/comments?post=10469"}],"version-history":[{"count":0,"href":"https:\/\/www.hangzhiprecision.com\/de_at\/wp-json\/wp\/v2\/posts\/10469\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hangzhiprecision.com\/de_at\/wp-json\/wp\/v2\/media\/10480"}],"wp:attachment":[{"href":"https:\/\/www.hangzhiprecision.com\/de_at\/wp-json\/wp\/v2\/media?parent=10469"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hangzhiprecision.com\/de_at\/wp-json\/wp\/v2\/categories?post=10469"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hangzhiprecision.com\/de_at\/wp-json\/wp\/v2\/tags?post=10469"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}